{"id":9307,"date":"2021-03-15T15:54:49","date_gmt":"2021-03-15T10:24:49","guid":{"rendered":"https:\/\/uem.edu.in\/uem-kolkata\/?post_type=news_event&#038;p=9307"},"modified":"2021-03-15T15:55:02","modified_gmt":"2021-03-15T10:25:02","slug":"teachers-chef-olympiad-2021","status":"publish","type":"news_event","link":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/","title":{"rendered":"Teachers Chef Olympiad 2021"},"content":{"rendered":"<p>&#8221; Teachers Chef Olympiad &#8221; 2021<br \/>\nUEM Kolkata Hotel Management School \u2013 IIIHM successfully conducted their mega event &#8220;Teachers Chef Olympiad&#8221;. Participation by teachers from reputed schools and the efforts of BHM students &amp; faculty members made the event a grand success.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9308\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-45-1\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.45 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1-768x1024.jpeg\" class=\"alignnone size-medium wp-image-9308\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1-225x300.jpeg 225w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1-768x1024.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9309\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-45\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.45\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1024x768.jpeg\" class=\"alignnone size-medium wp-image-9309\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-300x225.jpeg 300w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-1024x768.jpeg 1024w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45-768x576.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9310\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-44-1\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.44 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1-768x1024.jpeg\" class=\"alignnone size-medium wp-image-9310\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1-225x300.jpeg 225w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1-768x1024.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9311\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-44\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.44\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1024x768.jpeg\" class=\"alignnone size-medium wp-image-9311\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-300x225.jpeg 300w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-1024x768.jpeg 1024w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44-768x576.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.44.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9312\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-43-1\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1.jpeg\" data-orig-size=\"1152,864\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.43 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1-1024x768.jpeg\" class=\"alignnone size-medium wp-image-9312\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1-300x225.jpeg 300w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1-1024x768.jpeg 1024w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1-768x576.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1.jpeg 1152w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9313\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-43\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.43\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1024x768.jpeg\" class=\"alignnone size-medium wp-image-9313\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-300x225.jpeg 300w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-1024x768.jpeg 1024w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43-768x576.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.43.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9314\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-42-2\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.42 (2)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2-1024x768.jpeg\" class=\"alignnone size-medium wp-image-9314\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2-300x225.jpeg 300w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2-1024x768.jpeg 1024w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2-768x576.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-2.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9315\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-42-1\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-1.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.42 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-1-768x1024.jpeg\" class=\"alignnone size-medium wp-image-9315\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-1-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-1-225x300.jpeg 225w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-1-768x1024.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-1.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9316\" data-permalink=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/whatsapp-image-2021-03-15-at-15-12-42\/\" data-orig-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2021-03-15 at 15.12.42\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-768x1024.jpeg\" class=\"alignnone size-medium wp-image-9316\" src=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-225x300.jpeg 225w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42-768x1024.jpeg 768w, https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.42.jpeg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8221; Teachers Chef Olympiad &#8221; 2021 UEM Kolkata Hotel Management School \u2013 IIIHM successfully conducted their mega event &#8220;Teachers Chef Olympiad&#8221;. Participation by teachers from reputed schools and the efforts of BHM students &amp; faculty members made the event a grand success.<\/p>\n","protected":false},"author":17,"featured_media":9309,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"tags":[67,54],"class_list":["post-9307","news_event","type-news_event","status-publish","has-post-thumbnail","hentry","tag-other-events","tag-university-daily-news","wpautop"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teachers Chef Olympiad 2021 - UEM Kolkata<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teachers Chef Olympiad 2021 - UEM Kolkata\" \/>\n<meta property=\"og:description\" content=\"&#8221; Teachers Chef Olympiad &#8221; 2021 UEM Kolkata Hotel Management School \u2013 IIIHM successfully conducted their mega event &#8220;Teachers Chef Olympiad&#8221;. Participation by teachers from reputed schools and the efforts of BHM students &amp; faculty members made the event a grand success.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"UEM Kolkata\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-15T10:25:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/uemgroup.s3.amazonaws.com\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg?fit=1280%2C960&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/\",\"url\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/\",\"name\":\"Teachers Chef Olympiad 2021 - UEM Kolkata\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.uem.edu.in\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg\",\"datePublished\":\"2021-03-15T10:24:49+00:00\",\"dateModified\":\"2021-03-15T10:25:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.uem.edu.in\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg\",\"contentUrl\":\"https:\\\/\\\/media.uem.edu.in\\\/uploads\\\/sites\\\/2\\\/2021\\\/03\\\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/teachers-chef-olympiad-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News & Achievements\",\"item\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/news-events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Teachers Chef Olympiad 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/#website\",\"url\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/\",\"name\":\"UEM Kolkata\",\"description\":\"University of Engineering and Management Kolkata\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/uem.edu.in\\\/uem-kolkata\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teachers Chef Olympiad 2021 - UEM Kolkata","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Teachers Chef Olympiad 2021 - UEM Kolkata","og_description":"&#8221; Teachers Chef Olympiad &#8221; 2021 UEM Kolkata Hotel Management School \u2013 IIIHM successfully conducted their mega event &#8220;Teachers Chef Olympiad&#8221;. Participation by teachers from reputed schools and the efforts of BHM students &amp; faculty members made the event a grand success.","og_url":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/","og_site_name":"UEM Kolkata","article_modified_time":"2021-03-15T10:25:02+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/i0.wp.com\/uemgroup.s3.amazonaws.com\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg?fit=1280%2C960&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/","url":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/","name":"Teachers Chef Olympiad 2021 - UEM Kolkata","isPartOf":{"@id":"https:\/\/uem.edu.in\/uem-kolkata\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/#primaryimage"},"image":{"@id":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg","datePublished":"2021-03-15T10:24:49+00:00","dateModified":"2021-03-15T10:25:02+00:00","breadcrumb":{"@id":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/#primaryimage","url":"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg","contentUrl":"https:\/\/media.uem.edu.in\/uploads\/sites\/2\/2021\/03\/WhatsApp-Image-2021-03-15-at-15.12.45.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/teachers-chef-olympiad-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/uem.edu.in\/uem-kolkata\/"},{"@type":"ListItem","position":2,"name":"News & Achievements","item":"https:\/\/uem.edu.in\/uem-kolkata\/news-events\/"},{"@type":"ListItem","position":3,"name":"Teachers Chef Olympiad 2021"}]},{"@type":"WebSite","@id":"https:\/\/uem.edu.in\/uem-kolkata\/#website","url":"https:\/\/uem.edu.in\/uem-kolkata\/","name":"UEM Kolkata","description":"University of Engineering and Management Kolkata","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uem.edu.in\/uem-kolkata\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/news_event\/9307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/news_event"}],"about":[{"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/types\/news_event"}],"author":[{"embeddable":true,"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":1,"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/news_event\/9307\/revisions"}],"predecessor-version":[{"id":9317,"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/news_event\/9307\/revisions\/9317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/media\/9309"}],"wp:attachment":[{"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/media?parent=9307"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uem.edu.in\/uem-kolkata\/wp-json\/wp\/v2\/tags?post=9307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}